{"id":32,"date":"2024-11-24T04:02:24","date_gmt":"2024-11-24T04:02:24","guid":{"rendered":"https:\/\/wp.fleexstudio.com\/recrute\/?page_id=32"},"modified":"2025-03-13T00:26:50","modified_gmt":"2025-03-13T00:26:50","slug":"contact","status":"publish","type":"page","link":"https:\/\/hiring.marmacore.online\/index.php\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"32\" class=\"elementor elementor-32\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58ecb1b e-con-full e-flex e-con e-parent\" data-id=\"58ecb1b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c95bd69 elementor-widget elementor-widget-vl-contact\" data-id=\"c95bd69\" data-element_type=\"widget\" data-widget_type=\"vl-contact.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n<div class=\"contact-page sp\">\n     <div class=\"container\">\n          <div class=\"row align-items-center\">\n               <div class=\"col-lg-6\">\n                    <div class=\"heading1\">\n\n                                                  <span class=\"span\">Contact Us<\/span>\n                         \n                                                  <h2>Get in Touch Lets Start the Conversation<\/h2>\n                         \n                                                  <div class=\"space16\"><\/div>\n                         <p>We are here to help you find the right staffing solutions for your needs. Whether you are a company looking to hire top talent or a candidate seeking your next career opportunity<\/p>\n                         \n                    <\/div>\n\n                    <div class=\"contact-page-box\">\n                         <div class=\"row\">\n\n                                                            <div class=\"col-lg-6\">\n                                   <div class=\"contact-box\">\n                                                                                <div class=\"icon\">\n                                             <img decoding=\"async\" src=\"https:\/\/wp.fleexstudio.com\/recrute\/wp-content\/uploads\/2024\/12\/Group.png\"\n                                                  alt=\"\">\n                                        <\/div>\n                                                                                <div class=\"heading1\">\n                                                                                          <p>Gives us a Call<\/p>\n                                                                                                                                       <h4><a\n                                                       href=\"#\">123-456-7890<\/a>\n                                             <\/h4>\n                                                                                     <\/div>\n                                   <\/div>\n                              <\/div>\n                                                            <div class=\"col-lg-6\">\n                                   <div class=\"contact-box\">\n                                                                                <div class=\"icon\">\n                                             <img decoding=\"async\" src=\"https:\/\/wp.fleexstudio.com\/recrute\/wp-content\/uploads\/2024\/12\/Group-1.png\"\n                                                  alt=\"\">\n                                        <\/div>\n                                                                                <div class=\"heading1\">\n                                                                                          <p>Send me Mail<\/p>\n                                                                                                                                       <h4><a\n                                                       href=\"#\">Consult@hotmail.com<\/a>\n                                             <\/h4>\n                                                                                     <\/div>\n                                   <\/div>\n                              <\/div>\n                              \n                         <\/div>\n                    <\/div>\n               <\/div>\n\n               <div class=\"col-lg-6\">\n                    <div class=\"contact1-form\">\n                         <div class=\"heading1\">\n\n                                                            <h3>Send us a Message<\/h3>\n                              \n                                                            <div class=\"space16\"><\/div>\n                              <p>Feel free to reach out to us with any questions, inquiries, or staffing requirements you may have. Our experienced<\/p>\n                              \n                         <\/div>\n                         <div class=\"space10\"><\/div>\n\n                         <div class=\"recrute-form\">\n                              \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f793-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"793\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/32#wpcf7-f793-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"793\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0.5\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f793-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<div class=\"row\">\n                                   <div class=\"col-md-6\">\n                                        <div class=\"single-input\">\n                                             <span class=\"wpcf7-form-control-wrap\" data-name=\"text-16\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"First Name\" value=\"\" type=\"text\" name=\"text-16\" \/><\/span>\n                                        <\/div>\n                                   <\/div>\n\n                                   <div class=\"col-md-6\">\n                                        <div class=\"single-input\">\n                                             <span class=\"wpcf7-form-control-wrap\" data-name=\"text-688\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Last Name\" value=\"\" type=\"text\" name=\"text-688\" \/><\/span>\n                                        <\/div>\n                                   <\/div>\n\n                                   <div class=\"col-md-6\">\n                                        <div class=\"single-input\">\n                                             <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n                                        <\/div>\n                                   <\/div>\n\n                                   <div class=\"col-md-6\">\n                                        <div class=\"single-input\">\n                                             <span class=\"wpcf7-form-control-wrap\" data-name=\"tel-919\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" placeholder=\"Phone Number\" value=\"\" type=\"tel\" name=\"tel-919\" \/><\/span>\n                                        <\/div>\n                                   <\/div>\n\n                                   <div class=\"col-md-12\">\n                                        <div class=\"single-input\">\n                                             <span class=\"wpcf7-form-control-wrap\" data-name=\"text-891\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Subject\" value=\"\" type=\"text\" name=\"text-891\" \/><\/span>\n                                        <\/div>\n                                   <\/div>\n\n                                   <div class=\"col-md-12\">\n                                        <div class=\"single-input\">\n                                             <span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-14\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"You Message\" name=\"textarea-14\"><\/textarea><\/span>\n                                        <\/div>\n                                   <\/div>\n\n                                   <div class=\"col-md-12\">\n<div class=\"space20\"><\/div>\n                                        <div class=\"button\">\n<button class=\"theme-btn1\">Submit Now <span><i class=\"fa-solid fa-arrow-right\"><\/i><\/span><\/button>\n                                             \n                                        <\/div>\n                                   <\/div>\n\n                              <\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n                         <\/div>\n                    <\/div>\n               <\/div>\n\n          <\/div>\n     <\/div>\n<\/div>\n\n\n\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f6c948b e-con-full e-flex e-con e-parent\" data-id=\"f6c948b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-501e8f5 elementor-widget elementor-widget-google_maps\" data-id=\"501e8f5\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=London%20Eye%2C%20London%2C%20United%20Kingdom&#038;t=m&#038;z=12&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"London Eye, London, United Kingdom\"\n\t\t\t\t\taria-label=\"London Eye, London, United Kingdom\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Contact Us Get in Touch Lets Start the Conversation We are here to help you find the right staffing solutions for your needs. Whether you are a company looking to hire top talent or a candidate seeking your next career opportunity Gives us a Call 123-456-7890 Send me Mail Consult@hotmail.com Send us a Message Feel [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-32","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hiring.marmacore.online\/index.php\/wp-json\/wp\/v2\/pages\/32","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hiring.marmacore.online\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hiring.marmacore.online\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hiring.marmacore.online\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hiring.marmacore.online\/index.php\/wp-json\/wp\/v2\/comments?post=32"}],"version-history":[{"count":1,"href":"https:\/\/hiring.marmacore.online\/index.php\/wp-json\/wp\/v2\/pages\/32\/revisions"}],"predecessor-version":[{"id":2565,"href":"https:\/\/hiring.marmacore.online\/index.php\/wp-json\/wp\/v2\/pages\/32\/revisions\/2565"}],"wp:attachment":[{"href":"https:\/\/hiring.marmacore.online\/index.php\/wp-json\/wp\/v2\/media?parent=32"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}